{"id":906,"date":"2024-05-15T18:11:51","date_gmt":"2024-05-15T18:11:51","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/?post_type=process-category&#038;p=906"},"modified":"2025-10-22T20:40:04","modified_gmt":"2025-10-22T20:40:04","slug":"plant-based-proteins","status":"publish","type":"process-category","link":"https:\/\/onecpm.com\/es\/process-category\/plant-based-proteins","title":{"rendered":"Prote\u00ednas de origen vegetal"},"content":{"rendered":"<div id=\"process-hero\" class=\"nmc-block nmc-block--masthead-process-cat block-container alignfull -mode-dark\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"masthead-media -overlay\">\n\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t<source media=\"(max-width: 499px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:338,v:1\/cpm\/wp-content\/uploads\/2024\/08\/processes-plantbasedprotein-hero.jpg?s=574332d8\">\n\t\t\t<source media=\"(max-width: 899px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:1200,h:675,v:1\/cpm\/wp-content\/uploads\/2024\/08\/processes-plantbasedprotein-hero.jpg?s=ce1cf908\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" loading=\"eager\" style=\"aspect-ratio: 1.7777777777778;\" src=\"https:\/\/img.nmcdn.io\/e1\/w:1800,h:1013,v:1\/cpm\/wp-content\/uploads\/2024\/08\/processes-plantbasedprotein-hero.jpg?s=68a9ca0a\" width=\"1800\" height=\"1013\" alt=\"plant based protein\">\n\t\t<\/picture>\n\t<\/div>\n\t\t<\/div>\n<div class=\"bound boundwider\">\n\t<div class=\"masthead-content\">\n\t\t<p class=\"is-style-eyebrow-heading\">Procesos<\/p>\n\t\t<h1 class=\"page-title\">Prote\u00ednas de origen vegetal<\/h1>\n\t\t<div class=\"page-intro\"><p>Soluciones innovadoras para alimentar el futuro<\/p>\n<\/div>\t\t\t<\/div>\n<\/div>\n\n<script>\n(function(){\n\tdocument.documentElement.classList.add('-transparent-header');\n})();\n<\/script>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\t\n<div id=\"block_0999a91f1d7ad9b1a307e7ee39fffb4f\" class=\"nmc-block nmc-block--background block-container alignfull -mode-red filled padding-double\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"gutenberg\">\n\t\n\n<p class=\"has-text-align-center is-style-eyebrow-heading\">\u00daLTIMA INNOVACI\u00d3N<\/p>\n\n\n\n<p class=\"has-text-align-center is-style-heading-3\">Procesamiento limpio de semillas oleaginosas Monarc\u2122<\/p>\n\n\n\n<p class=\"has-text-align-center\">Seguro. Escalable. Sostenible. Sin hexano.<\/p>\n\n\n\n\n\n\t\t\t\t\n\t\n<div class=\"nmc-block nmc-block--buttons button-align-center\" id=\"block_2381f1fb9e762e419c362a290d559605\">\n\t<div class=\"blockbody\">\n\t\n\t\t\t\t\t\t\n\t\t<a href=\"https:\/\/onecpm.com\/es\/landing-monarc\/\" class=\"btn -btn\" >Aprende m\u00e1s<\/a>\n\t\t<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n<style>\ndiv#process-hero.nmc-block {\n    margin-bottom: 0;\n}\n<\/style>\n\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_473647fbb255cbba19cefd5bb6e71d9e\" class=\"nmc-block nmc-block--intro-contact block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t\t\t<div class=\"wrap\">\n\n\t\t\t<div class=\"content\">\n\t\t\t\t\n\t\t\t\t                                                                                                                                                                                                    <h2 class=\"block-title\">Nuevas posibilidades para la <strong>El futuro de la alimentaci\u00f3n<\/strong><\/h2>\t\t\t\t<p>Las prote\u00ednas de origen vegetal est\u00e1n revolucionando el futuro de los alimentos. Son esenciales en los alimentos para acuicultura, alimentos para mascotas, nutrici\u00f3n del ganado, biopl\u00e1sticos, textiles, pel\u00edculas comestibles, recubrimientos y m\u00e1s. Desde la viabilidad, los ensayos y el procesamiento personalizado hasta las operaciones a gran escala comercial, la experiencia de CPM, junto con la I+D, brindan orientaci\u00f3n y apoyo en cada paso. Para el descascarado, el desgrasado, los copos blancos y el concentrado de prote\u00ednas, las tecnolog\u00edas de prote\u00ednas vegetales y las soluciones de ingenier\u00eda personalizadas de CPM le permiten desarrollar y producir productos consistentes con la m\u00e1s alta calidad de prote\u00ednas.<\/p>\n\n\t\t\t<\/div>\n\n\t\t\t<div class=\"sidebar -crown-logo\">\n\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/onecpm.com\/wp-content\/themes\/nmc_cpm\/assets\/crown-logo.png\" width=\"250\" height=\"102\" alt=\"Crown\" loading=\"lazy\">\n\t\t\t\t\n\t\t\t\t<div class=\"sidebar-content\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"\/es\/about-cpm\/contact-us\/\" class=\"btn contact\">Contacto Ventas<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<p><a href=\"tel:&lt;ahref=&quot;https:\/\/onecpmcom\/aboutcpm\/locations&quot;&gt;Viewallglobalnumbers&lt;\/a&gt;\"><a href=\"https:\/\/onecpm.com\/es\/about-cpm\/locations\/\">Ver todos los n\u00fameros globales<\/a><\/a><\/p>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/brand\/crown\/\" target=\"\">Visita Crown<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/e1.nmcdn.io\/assets\/cpm\/wp-content\/uploads\/2024\/07\/Plant-based-Protein_Process-System_4-pager_June-2024.pdf\" target=\"_blank\" class=\"btn -outline\">Descargar folleto <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"11\" height=\"5\" viewbox=\"0 0 11 5\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><path d=\"M2.03533 0.292093L2.03532 0.292106L5.48831 3.34242L8.9654 0.291342C9.2645 0.0218744 9.65745 0.115818 9.88955 0.315501C10.0076 0.417024 10.0988 0.556406 10.1203 0.712296C10.1425 0.874276 10.0869 1.03846 9.93933 1.17178L9.93934 1.17179L9.93814 1.17284L5.90306 4.72584L5.90307 4.72585L5.90198 4.72679C5.79368 4.81995 5.64645 4.86827 5.50539 4.87434C5.36466 4.8804 5.21168 4.84498 5.09805 4.74722L5.09804 4.74723L5.0967 4.74604L1.06162 1.17272L1.06162 1.17273L1.0607 1.1719C0.913121 1.03859 0.857452 0.874405 0.879725 0.712422C0.901161 0.55653 0.992442 0.417153 1.11045 0.315634C1.34275 0.115805 1.73615 0.021872 2.03533 0.292093Z\" fill=\"#2A2723\" stroke=\"#2A2723\" stroke-width=\"0.25\"\/><\/svg><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_7620a2937c4cddf1b9d3c7fb2d1d0397\" class=\"nmc-block nmc-block--related-resources block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t<div class=\"block-intro\">\n\t\t\t                                                                        <h2 class=\"block-title\">Recursos relacionados<\/h2>\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/resource-library\/\" target=\"\" class=\"btn -non-btn\">Ver todo <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"12\" viewbox=\"0 0 17 12\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>arrow<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.9176 6.28571L8.65133 10.5863L9.42733 11.4286L16.3999 5.71429L9.41476 0L8.65362 0.860571L13.9153 5.14286L0.399902 5.14286L0.399902 6.28571L13.9176 6.28571Z\" fill=\"white\"\/>\n<\/svg><\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"slider-wrap\">\n\t\t\t<div id=\"slider-block_7620a2937c4cddf1b9d3c7fb2d1d0397-slider\" class=\"nmc-slider scrollable snaps\" data-nmc-slider data-nmc-slider-loop role=\"region\" aria-label=\"Carrusel de vista previa de contenido\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" role=\"group\" aria-label=\"Diapositiva 1 de 4\" aria-current=\"true\">\n\t\t\t\t\t\t\n<div class=\"partial -resource -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/resource\/specialty-products-extraction\" target=\"_blank\" class=\"link\">Extracci\u00f3n de productos especiales<\/a>\n        <\/h3>\n                    <div class=\"excerpt\">Para los mercados emergentes y existentes, Crown ofrece soluciones integrales respaldadas por 70 a\u00f1os de experiencia en extracci\u00f3n. <\/div>\n            <\/div>\n    <div class=\"download-bottom\" aria-hidden=\"true\">\n                    Acceder al recurso <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>download<\/title>\n    <path d=\"M8.99872 4.82129C8.90339 4.82129 8.81192 4.85915 8.74451 4.92656C8.67704 4.99403 8.63918 5.08543 8.63918 5.18083V10.7537L6.39926 8.50295C6.30838 8.41207 6.1759 8.37655 6.05178 8.40979C5.92767 8.44309 5.83064 8.54005 5.79741 8.66416C5.76417 8.78834 5.79964 8.92077 5.89051 9.01164L8.74524 11.8664C8.76203 11.8827 8.78005 11.8977 8.79919 11.9113H8.81359L8.86034 11.9365H8.88194H8.88188C8.89692 11.9426 8.9126 11.9468 8.92863 11.949C8.95192 11.9518 8.97545 11.9518 8.99874 11.949C9.02261 11.9517 9.04672 11.9517 9.07066 11.949C9.08605 11.9465 9.10115 11.9423 9.1156 11.9365H9.13719L9.18395 11.9113H9.19834L9.25406 11.8664L12.107 9.01164C12.1979 8.92076 12.2333 8.78834 12.2001 8.66416C12.1668 8.54004 12.0698 8.44308 11.9457 8.40979C11.8216 8.37655 11.6891 8.41207 11.5982 8.50295L9.35832 10.7447V5.18083C9.35832 5.08545 9.32046 4.99404 9.25299 4.92656C9.18557 4.85915 9.09412 4.82129 8.99878 4.82129H8.99872Z\" fill=\"white\"\/>\n    <path d=\"M6.14472 13.4754H11.8542C11.9826 13.4754 12.1013 13.4069 12.1655 13.2957C12.2298 13.1844 12.2298 13.0474 12.1655 12.9361C12.1013 12.8249 11.9826 12.7563 11.8542 12.7563H6.14472C6.01627 12.7563 5.89754 12.8249 5.83335 12.9361C5.76909 13.0474 5.76909 13.1844 5.83335 13.2957C5.89754 13.4069 6.01628 13.4754 6.14472 13.4754Z\" fill=\"white\"\/>\n    <circle cx=\"9\" cy=\"9\" r=\"8.5\" stroke=\"white\"\/>\n<\/svg>            <\/div>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" role=\"group\" aria-label=\"Diapositiva 2 de 4\" >\n\t\t\t\t\t\t\n<div class=\"partial -resource -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/resource\/plant-based-protein-concentrate-process-system\" target=\"_blank\" class=\"link\">Sistema de proceso de concentrado de prote\u00edna de origen vegetal<\/a>\n        <\/h3>\n                    <div class=\"excerpt\">Diversifique su negocio en prote\u00ednas de origen vegetal con la experiencia de CPM Crown.<\/div>\n            <\/div>\n    <div class=\"download-bottom\" aria-hidden=\"true\">\n                    Acceder al recurso <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>download<\/title>\n    <path d=\"M8.99872 4.82129C8.90339 4.82129 8.81192 4.85915 8.74451 4.92656C8.67704 4.99403 8.63918 5.08543 8.63918 5.18083V10.7537L6.39926 8.50295C6.30838 8.41207 6.1759 8.37655 6.05178 8.40979C5.92767 8.44309 5.83064 8.54005 5.79741 8.66416C5.76417 8.78834 5.79964 8.92077 5.89051 9.01164L8.74524 11.8664C8.76203 11.8827 8.78005 11.8977 8.79919 11.9113H8.81359L8.86034 11.9365H8.88194H8.88188C8.89692 11.9426 8.9126 11.9468 8.92863 11.949C8.95192 11.9518 8.97545 11.9518 8.99874 11.949C9.02261 11.9517 9.04672 11.9517 9.07066 11.949C9.08605 11.9465 9.10115 11.9423 9.1156 11.9365H9.13719L9.18395 11.9113H9.19834L9.25406 11.8664L12.107 9.01164C12.1979 8.92076 12.2333 8.78834 12.2001 8.66416C12.1668 8.54004 12.0698 8.44308 11.9457 8.40979C11.8216 8.37655 11.6891 8.41207 11.5982 8.50295L9.35832 10.7447V5.18083C9.35832 5.08545 9.32046 4.99404 9.25299 4.92656C9.18557 4.85915 9.09412 4.82129 8.99878 4.82129H8.99872Z\" fill=\"white\"\/>\n    <path d=\"M6.14472 13.4754H11.8542C11.9826 13.4754 12.1013 13.4069 12.1655 13.2957C12.2298 13.1844 12.2298 13.0474 12.1655 12.9361C12.1013 12.8249 11.9826 12.7563 11.8542 12.7563H6.14472C6.01627 12.7563 5.89754 12.8249 5.83335 12.9361C5.76909 13.0474 5.76909 13.1844 5.83335 13.2957C5.89754 13.4069 6.01628 13.4754 6.14472 13.4754Z\" fill=\"white\"\/>\n    <circle cx=\"9\" cy=\"9\" r=\"8.5\" stroke=\"white\"\/>\n<\/svg>            <\/div>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" role=\"group\" aria-label=\"Diapositiva 3 de 4\" >\n\t\t\t\t\t\t\n<div class=\"partial -resource -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/resource\/crown-global-innovation-center-video\" target=\"_blank\" class=\"link\">V\u00eddeo del Centro de Innovaci\u00f3n Global Crown<\/a>\n        <\/h3>\n                    <div class=\"excerpt\">Obtenga m\u00e1s informaci\u00f3n sobre el Centro de Innovaci\u00f3n Global Crown de CPM.<\/div>\n            <\/div>\n    <div class=\"download-bottom\" aria-hidden=\"true\">\n                    Acceder al recurso <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>download<\/title>\n    <path d=\"M8.99872 4.82129C8.90339 4.82129 8.81192 4.85915 8.74451 4.92656C8.67704 4.99403 8.63918 5.08543 8.63918 5.18083V10.7537L6.39926 8.50295C6.30838 8.41207 6.1759 8.37655 6.05178 8.40979C5.92767 8.44309 5.83064 8.54005 5.79741 8.66416C5.76417 8.78834 5.79964 8.92077 5.89051 9.01164L8.74524 11.8664C8.76203 11.8827 8.78005 11.8977 8.79919 11.9113H8.81359L8.86034 11.9365H8.88194H8.88188C8.89692 11.9426 8.9126 11.9468 8.92863 11.949C8.95192 11.9518 8.97545 11.9518 8.99874 11.949C9.02261 11.9517 9.04672 11.9517 9.07066 11.949C9.08605 11.9465 9.10115 11.9423 9.1156 11.9365H9.13719L9.18395 11.9113H9.19834L9.25406 11.8664L12.107 9.01164C12.1979 8.92076 12.2333 8.78834 12.2001 8.66416C12.1668 8.54004 12.0698 8.44308 11.9457 8.40979C11.8216 8.37655 11.6891 8.41207 11.5982 8.50295L9.35832 10.7447V5.18083C9.35832 5.08545 9.32046 4.99404 9.25299 4.92656C9.18557 4.85915 9.09412 4.82129 8.99878 4.82129H8.99872Z\" fill=\"white\"\/>\n    <path d=\"M6.14472 13.4754H11.8542C11.9826 13.4754 12.1013 13.4069 12.1655 13.2957C12.2298 13.1844 12.2298 13.0474 12.1655 12.9361C12.1013 12.8249 11.9826 12.7563 11.8542 12.7563H6.14472C6.01627 12.7563 5.89754 12.8249 5.83335 12.9361C5.76909 13.0474 5.76909 13.1844 5.83335 13.2957C5.89754 13.4069 6.01628 13.4754 6.14472 13.4754Z\" fill=\"white\"\/>\n    <circle cx=\"9\" cy=\"9\" r=\"8.5\" stroke=\"white\"\/>\n<\/svg>            <\/div>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" role=\"group\" aria-label=\"Diapositiva 4 de 4\" >\n\t\t\t\t\t\t\n<div class=\"partial -resource -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/resource\/cpm-crown-specialty-products-processes\" target=\"_blank\" class=\"link\">CPM Crown: Productos y procesos especiales<\/a>\n        <\/h3>\n                    <div class=\"excerpt\">CPM Crown es un l\u00edder mundial e innovador en el procesamiento de semillas oleaginosas, que ofrece ingenier\u00eda de procesos personalizados, equipos, pilotaje y soporte posventa para trituraci\u00f3n, refinaci\u00f3n, biocombustibles, oleoqu\u00edmicos, prote\u00ednas de origen vegetal y otras extracciones especiales. <\/div>\n            <\/div>\n    <div class=\"download-bottom\" aria-hidden=\"true\">\n                    Acceder al recurso <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewbox=\"0 0 18 18\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>download<\/title>\n    <path d=\"M8.99872 4.82129C8.90339 4.82129 8.81192 4.85915 8.74451 4.92656C8.67704 4.99403 8.63918 5.08543 8.63918 5.18083V10.7537L6.39926 8.50295C6.30838 8.41207 6.1759 8.37655 6.05178 8.40979C5.92767 8.44309 5.83064 8.54005 5.79741 8.66416C5.76417 8.78834 5.79964 8.92077 5.89051 9.01164L8.74524 11.8664C8.76203 11.8827 8.78005 11.8977 8.79919 11.9113H8.81359L8.86034 11.9365H8.88194H8.88188C8.89692 11.9426 8.9126 11.9468 8.92863 11.949C8.95192 11.9518 8.97545 11.9518 8.99874 11.949C9.02261 11.9517 9.04672 11.9517 9.07066 11.949C9.08605 11.9465 9.10115 11.9423 9.1156 11.9365H9.13719L9.18395 11.9113H9.19834L9.25406 11.8664L12.107 9.01164C12.1979 8.92076 12.2333 8.78834 12.2001 8.66416C12.1668 8.54004 12.0698 8.44308 11.9457 8.40979C11.8216 8.37655 11.6891 8.41207 11.5982 8.50295L9.35832 10.7447V5.18083C9.35832 5.08545 9.32046 4.99404 9.25299 4.92656C9.18557 4.85915 9.09412 4.82129 8.99878 4.82129H8.99872Z\" fill=\"white\"\/>\n    <path d=\"M6.14472 13.4754H11.8542C11.9826 13.4754 12.1013 13.4069 12.1655 13.2957C12.2298 13.1844 12.2298 13.0474 12.1655 12.9361C12.1013 12.8249 11.9826 12.7563 11.8542 12.7563H6.14472C6.01627 12.7563 5.89754 12.8249 5.83335 12.9361C5.76909 13.0474 5.76909 13.1844 5.83335 13.2957C5.89754 13.4069 6.01628 13.4754 6.14472 13.4754Z\" fill=\"white\"\/>\n    <circle cx=\"9\" cy=\"9\" r=\"8.5\" stroke=\"white\"\/>\n<\/svg>            <\/div>\n<\/div>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_515fda157332bd8fec381bd453f45181\" class=\"nmc-block nmc-block--multicolumn-partials block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t<div class=\"content-wrap\">\n\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"is-style-eyebrow-heading\">Explorar procesos<\/p>\n\t\t\t\t\t\t\t\t                                                                                                                                            <h2 class=\"block-title\">El papel de CPM en las prote\u00ednas de origen vegetal<\/h2>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t<div class=\"listing-wrapper -columns-2\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"partial-container\">\n\t\t\t\t\t<div class=\"partial\">\n\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t<h3 class=\"heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/process\/protein-concentrate\/\" target=\"\" class=\"link\"><span>Concentrado de prote\u00edna\/Extracci\u00f3n con etanol hidratado<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewbox=\"0 0 26 26\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n<mask class=\"path-1-inside-1_2439_3058\" fill=\"white\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\"\/>\n<\/mask>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\" fill=\"#CC092F\"\/>\n<path d=\"M16.6399 13.5496L17.2724 14.3242L19.4454 12.5496H16.6399V13.5496ZM12.7999 16.6855L12.1674 15.9109L11.3452 16.5824L12.0644 17.3631L12.7999 16.6855ZM13.3657 17.2996L12.6303 17.9772L13.2697 18.6713L13.9996 18.0731L13.3657 17.2996ZM18.4499 13.133L19.0837 13.9064L20.0283 13.1323L19.0831 12.359L18.4499 13.133ZM13.3565 8.96631L13.9897 8.19231L13.245 7.58305L12.6075 8.3038L13.3565 8.96631ZM12.8015 9.59381L12.0525 8.9313L11.3622 9.71174L12.1703 10.3694L12.8015 9.59381ZM16.6382 12.7163V13.7163H19.4511L17.2694 11.9407L16.6382 12.7163ZM6.7832 12.7163V11.7163H5.7832V12.7163H6.7832ZM6.7832 13.5496H5.7832V14.5496H6.7832V13.5496ZM16.0074 12.7751L12.1674 15.9109L13.4324 17.46L17.2724 14.3242L16.0074 12.7751ZM12.0644 17.3631L12.6303 17.9772L14.1012 16.6221L13.5353 16.0079L12.0644 17.3631ZM13.9996 18.0731L19.0837 13.9064L17.816 12.3595L12.7318 16.5262L13.9996 18.0731ZM19.0831 12.359L13.9897 8.19231L12.7234 9.74031L17.8167 13.907L19.0831 12.359ZM12.6075 8.3038L12.0525 8.9313L13.5506 10.2563L14.1056 9.62882L12.6075 8.3038ZM12.1703 10.3694L16.007 13.4919L17.2694 11.9407L13.4328 8.81821L12.1703 10.3694ZM16.6382 11.7163H6.7832V13.7163H16.6382V11.7163ZM5.7832 12.7163V13.5496H7.7832V12.7163H5.7832ZM6.7832 14.5496H16.6399V12.5496H6.7832V14.5496Z\" fill=\"#CC092F\" mask=\"url(.path-1-inside-1_2439_3058)\"\/>\n<circle cx=\"12.6172\" cy=\"13.1329\" r=\"12\" stroke=\"#CC092F\"\/>\n<\/svg><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<div class=\"excerpt\">Nuestra experiencia garantiza una extracci\u00f3n eficiente, la eliminaci\u00f3n de antinutrientes y el refinamiento de prote\u00ednas, lo que da como resultado concentrados superiores ideales para alimentos de consumo, alimentos acu\u00edcolas y otras aplicaciones. Al aprovechar nuestras tecnolog\u00edas avanzadas dise\u00f1adas a medida y d\u00e9cadas de experiencia, CPM lo ayuda a maximizar el rendimiento, mejorar la calidad del producto y satisfacer la creciente demanda de fuentes de prote\u00ednas sustentables.<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\n<div class=\"image-auto\" style=\"aspect-ratio: 600 \/ 340;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:272,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-plantbasedprotein-proteinconcentrate-1.jpg?s=2b19fae9\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:340,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-plantbasedprotein-proteinconcentrate-1.jpg?s=d597f060\" width=\"600\" height=\"340\" alt=\"\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"partial-container\">\n\t\t\t\t\t<div class=\"partial\">\n\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t<h3 class=\"heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/process\/white-flakes\/\" target=\"\" class=\"link\"><span>Copos blancos<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewbox=\"0 0 26 26\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n<mask class=\"path-1-inside-1_2439_3058\" fill=\"white\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\"\/>\n<\/mask>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\" fill=\"#CC092F\"\/>\n<path d=\"M16.6399 13.5496L17.2724 14.3242L19.4454 12.5496H16.6399V13.5496ZM12.7999 16.6855L12.1674 15.9109L11.3452 16.5824L12.0644 17.3631L12.7999 16.6855ZM13.3657 17.2996L12.6303 17.9772L13.2697 18.6713L13.9996 18.0731L13.3657 17.2996ZM18.4499 13.133L19.0837 13.9064L20.0283 13.1323L19.0831 12.359L18.4499 13.133ZM13.3565 8.96631L13.9897 8.19231L13.245 7.58305L12.6075 8.3038L13.3565 8.96631ZM12.8015 9.59381L12.0525 8.9313L11.3622 9.71174L12.1703 10.3694L12.8015 9.59381ZM16.6382 12.7163V13.7163H19.4511L17.2694 11.9407L16.6382 12.7163ZM6.7832 12.7163V11.7163H5.7832V12.7163H6.7832ZM6.7832 13.5496H5.7832V14.5496H6.7832V13.5496ZM16.0074 12.7751L12.1674 15.9109L13.4324 17.46L17.2724 14.3242L16.0074 12.7751ZM12.0644 17.3631L12.6303 17.9772L14.1012 16.6221L13.5353 16.0079L12.0644 17.3631ZM13.9996 18.0731L19.0837 13.9064L17.816 12.3595L12.7318 16.5262L13.9996 18.0731ZM19.0831 12.359L13.9897 8.19231L12.7234 9.74031L17.8167 13.907L19.0831 12.359ZM12.6075 8.3038L12.0525 8.9313L13.5506 10.2563L14.1056 9.62882L12.6075 8.3038ZM12.1703 10.3694L16.007 13.4919L17.2694 11.9407L13.4328 8.81821L12.1703 10.3694ZM16.6382 11.7163H6.7832V13.7163H16.6382V11.7163ZM5.7832 12.7163V13.5496H7.7832V12.7163H5.7832ZM6.7832 14.5496H16.6399V12.5496H6.7832V14.5496Z\" fill=\"#CC092F\" mask=\"url(.path-1-inside-1_2439_3058)\"\/>\n<circle cx=\"12.6172\" cy=\"13.1329\" r=\"12\" stroke=\"#CC092F\"\/>\n<\/svg><\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<div class=\"excerpt\">Nuestras soluciones de procesamiento personalizadas y avanzadas extraen el aceite de manera eficiente y eliminan los antinutrientes, lo que garantiza la producci\u00f3n de hojuelas blancas de calidad superior listas para usos posteriores. Con nuestras d\u00e9cadas de experiencia y tecnolog\u00edas innovadoras, CPM respalda sus esfuerzos para satisfacer la creciente demanda de prote\u00ednas vegetales sustentables. <\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\n<div class=\"image-auto\" style=\"aspect-ratio: 1400 \/ 793;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:272,v:1\/cpm\/wp-content\/uploads\/2024\/08\/processes-plantbasedproteins-whiteflakes-hero.jpg?s=69077ddd\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:340,v:1\/cpm\/wp-content\/uploads\/2024\/08\/processes-plantbasedproteins-whiteflakes-hero.jpg?s=55746fb2\" width=\"1400\" height=\"793\" alt=\"plant based proteins white flakes\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\t\n<div id=\"block_741a31db2d581940776846c51eefbf1e\" class=\"nmc-block nmc-block--background block-container alignfull -mode-gray filled padding-quadruple\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"gutenberg\">\n\t\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_4430f03f7b271b2a731516142f5dbb49\" class=\"nmc-block nmc-block--product-slider block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t<div class=\"content-wrap\">\n\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"is-style-eyebrow-heading translation-block\"><strong>El equipaje<\/strong> relacionado<\/p>\n\t\t\t\t\t\t\t\t                                                                                                                                                                                                                <h2 class=\"block-title\">Equipo hecho para <strong>prote\u00edna vegetal<\/strong> tratamiento<\/h2>\t\t\t\t\n\t\t\t<\/div>\n\t\t\t<div class=\"links\">\n\t\t\t<a href=\"https:\/\/onecpm.com\/es\/equipment\/\" target=\"\" class=\"btn -non-btn\">Ver todos los equipos <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"12\" viewbox=\"0 0 17 12\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>arrow<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.9176 6.28571L8.65133 10.5863L9.42733 11.4286L16.3999 5.71429L9.41476 0L8.65362 0.860571L13.9153 5.14286L0.399902 5.14286L0.399902 6.28571L13.9176 6.28571Z\" fill=\"white\"\/>\n<\/svg><\/a>\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t<div class=\"slider-wrap\">\n\n\t\t\t\n\t\t\t<div id=\"slider-block_4430f03f7b271b2a731516142f5dbb49-slider\" class=\"nmc-slider scrollable snaps\" data-nmc-slider role=\"region\" aria-label=\"Carrusel de vista previa de contenido\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" id=\"slider-block_4430f03f7b271b2a731516142f5dbb49-slide-1\" role=\"group\" aria-label=\"Diapositiva 1 de 3\" aria-current=\"true\">\n\t\t\t\t\t\t\t<div class=\"partial-container\">\n\t\t\t\t\t\t\t\t\n<div class=\"partial -product -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/product-line\/extraction-equipment\" class=\"link\"><span>Equipo de extracci\u00f3n<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewbox=\"0 0 26 26\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n<mask class=\"path-1-inside-1_2439_3058\" fill=\"white\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\"\/>\n<\/mask>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\" fill=\"#CC092F\"\/>\n<path d=\"M16.6399 13.5496L17.2724 14.3242L19.4454 12.5496H16.6399V13.5496ZM12.7999 16.6855L12.1674 15.9109L11.3452 16.5824L12.0644 17.3631L12.7999 16.6855ZM13.3657 17.2996L12.6303 17.9772L13.2697 18.6713L13.9996 18.0731L13.3657 17.2996ZM18.4499 13.133L19.0837 13.9064L20.0283 13.1323L19.0831 12.359L18.4499 13.133ZM13.3565 8.96631L13.9897 8.19231L13.245 7.58305L12.6075 8.3038L13.3565 8.96631ZM12.8015 9.59381L12.0525 8.9313L11.3622 9.71174L12.1703 10.3694L12.8015 9.59381ZM16.6382 12.7163V13.7163H19.4511L17.2694 11.9407L16.6382 12.7163ZM6.7832 12.7163V11.7163H5.7832V12.7163H6.7832ZM6.7832 13.5496H5.7832V14.5496H6.7832V13.5496ZM16.0074 12.7751L12.1674 15.9109L13.4324 17.46L17.2724 14.3242L16.0074 12.7751ZM12.0644 17.3631L12.6303 17.9772L14.1012 16.6221L13.5353 16.0079L12.0644 17.3631ZM13.9996 18.0731L19.0837 13.9064L17.816 12.3595L12.7318 16.5262L13.9996 18.0731ZM19.0831 12.359L13.9897 8.19231L12.7234 9.74031L17.8167 13.907L19.0831 12.359ZM12.6075 8.3038L12.0525 8.9313L13.5506 10.2563L14.1056 9.62882L12.6075 8.3038ZM12.1703 10.3694L16.007 13.4919L17.2694 11.9407L13.4328 8.81821L12.1703 10.3694ZM16.6382 11.7163H6.7832V13.7163H16.6382V11.7163ZM5.7832 12.7163V13.5496H7.7832V12.7163H5.7832ZM6.7832 14.5496H16.6399V12.5496H6.7832V14.5496Z\" fill=\"#CC092F\" mask=\"url(.path-1-inside-1_2439_3058)\"\/>\n<circle cx=\"12.6172\" cy=\"13.1329\" r=\"12\" stroke=\"#CC092F\"\/>\n<\/svg><\/a>\n        <\/h3>\n        <div class=\"excerpt\">Soluciones de extracci\u00f3n de alto rendimiento<\/div>\n    <\/div>\n\n            <div class=\"image\">\n                            \n<div class=\"image-auto\" style=\"aspect-ratio: 600 \/ 361;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:289,v:1\/cpm\/wp-content\/uploads\/2024\/08\/crushspecialty-extraction-modelII-main.jpg?s=f278ca12\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:361,v:1\/cpm\/wp-content\/uploads\/2024\/08\/crushspecialty-extraction-modelII-main.jpg?s=9dca7927\" width=\"600\" height=\"361\" alt=\"Crush Specialty Model III Extractor Image\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n                    <\/div>\n\n    <\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" id=\"slider-block_4430f03f7b271b2a731516142f5dbb49-slide-2\" role=\"group\" aria-label=\"Diapositiva 2 de 3\" >\n\t\t\t\t\t\t\t<div class=\"partial-container\">\n\t\t\t\t\t\t\t\t\n<div class=\"partial -product -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/product-line\/dryers-desolventizers\" class=\"link\"><span>Secadores y Desolventizadores<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewbox=\"0 0 26 26\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n<mask class=\"path-1-inside-1_2439_3058\" fill=\"white\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\"\/>\n<\/mask>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\" fill=\"#CC092F\"\/>\n<path d=\"M16.6399 13.5496L17.2724 14.3242L19.4454 12.5496H16.6399V13.5496ZM12.7999 16.6855L12.1674 15.9109L11.3452 16.5824L12.0644 17.3631L12.7999 16.6855ZM13.3657 17.2996L12.6303 17.9772L13.2697 18.6713L13.9996 18.0731L13.3657 17.2996ZM18.4499 13.133L19.0837 13.9064L20.0283 13.1323L19.0831 12.359L18.4499 13.133ZM13.3565 8.96631L13.9897 8.19231L13.245 7.58305L12.6075 8.3038L13.3565 8.96631ZM12.8015 9.59381L12.0525 8.9313L11.3622 9.71174L12.1703 10.3694L12.8015 9.59381ZM16.6382 12.7163V13.7163H19.4511L17.2694 11.9407L16.6382 12.7163ZM6.7832 12.7163V11.7163H5.7832V12.7163H6.7832ZM6.7832 13.5496H5.7832V14.5496H6.7832V13.5496ZM16.0074 12.7751L12.1674 15.9109L13.4324 17.46L17.2724 14.3242L16.0074 12.7751ZM12.0644 17.3631L12.6303 17.9772L14.1012 16.6221L13.5353 16.0079L12.0644 17.3631ZM13.9996 18.0731L19.0837 13.9064L17.816 12.3595L12.7318 16.5262L13.9996 18.0731ZM19.0831 12.359L13.9897 8.19231L12.7234 9.74031L17.8167 13.907L19.0831 12.359ZM12.6075 8.3038L12.0525 8.9313L13.5506 10.2563L14.1056 9.62882L12.6075 8.3038ZM12.1703 10.3694L16.007 13.4919L17.2694 11.9407L13.4328 8.81821L12.1703 10.3694ZM16.6382 11.7163H6.7832V13.7163H16.6382V11.7163ZM5.7832 12.7163V13.5496H7.7832V12.7163H5.7832ZM6.7832 14.5496H16.6399V12.5496H6.7832V14.5496Z\" fill=\"#CC092F\" mask=\"url(.path-1-inside-1_2439_3058)\"\/>\n<circle cx=\"12.6172\" cy=\"13.1329\" r=\"12\" stroke=\"#CC092F\"\/>\n<\/svg><\/a>\n        <\/h3>\n        <div class=\"excerpt\">Soluciones de secado y desolventizaci\u00f3n de alto rendimiento<\/div>\n    <\/div>\n\n            <div class=\"image\">\n                            \n<div class=\"image-auto\" style=\"aspect-ratio: 483 \/ 648;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:644,v:1\/cpm\/wp-content\/uploads\/2024\/05\/DryersDesolventizers-cat-thumb.jpg?s=cc533fa4\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:805,v:1\/cpm\/wp-content\/uploads\/2024\/05\/DryersDesolventizers-cat-thumb.jpg?s=da0a9ef3\" width=\"483\" height=\"648\" alt=\"Vacuum Desolventizer Stripper (VDS)\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n                    <\/div>\n\n    <\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"nmc-slide\" id=\"slider-block_4430f03f7b271b2a731516142f5dbb49-slide-3\" role=\"group\" aria-label=\"Diapositiva 3 de 3\" >\n\t\t\t\t\t\t\t<div class=\"partial-container\">\n\t\t\t\t\t\t\t\t\n<div class=\"partial -product -card\">\n    <div class=\"text\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/product-line\/preparation-equipment\" class=\"link\"><span>Equipo de preparaci\u00f3n<\/span> <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"26\" height=\"26\" viewbox=\"0 0 26 26\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n<mask class=\"path-1-inside-1_2439_3058\" fill=\"white\">\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\"\/>\n<\/mask>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.6399 13.5496L12.7999 16.6855L13.3657 17.2996L18.4499 13.133L13.3565 8.96631L12.8015 9.59381L16.6382 12.7163H6.7832V13.5496H16.6399Z\" fill=\"#CC092F\"\/>\n<path d=\"M16.6399 13.5496L17.2724 14.3242L19.4454 12.5496H16.6399V13.5496ZM12.7999 16.6855L12.1674 15.9109L11.3452 16.5824L12.0644 17.3631L12.7999 16.6855ZM13.3657 17.2996L12.6303 17.9772L13.2697 18.6713L13.9996 18.0731L13.3657 17.2996ZM18.4499 13.133L19.0837 13.9064L20.0283 13.1323L19.0831 12.359L18.4499 13.133ZM13.3565 8.96631L13.9897 8.19231L13.245 7.58305L12.6075 8.3038L13.3565 8.96631ZM12.8015 9.59381L12.0525 8.9313L11.3622 9.71174L12.1703 10.3694L12.8015 9.59381ZM16.6382 12.7163V13.7163H19.4511L17.2694 11.9407L16.6382 12.7163ZM6.7832 12.7163V11.7163H5.7832V12.7163H6.7832ZM6.7832 13.5496H5.7832V14.5496H6.7832V13.5496ZM16.0074 12.7751L12.1674 15.9109L13.4324 17.46L17.2724 14.3242L16.0074 12.7751ZM12.0644 17.3631L12.6303 17.9772L14.1012 16.6221L13.5353 16.0079L12.0644 17.3631ZM13.9996 18.0731L19.0837 13.9064L17.816 12.3595L12.7318 16.5262L13.9996 18.0731ZM19.0831 12.359L13.9897 8.19231L12.7234 9.74031L17.8167 13.907L19.0831 12.359ZM12.6075 8.3038L12.0525 8.9313L13.5506 10.2563L14.1056 9.62882L12.6075 8.3038ZM12.1703 10.3694L16.007 13.4919L17.2694 11.9407L13.4328 8.81821L12.1703 10.3694ZM16.6382 11.7163H6.7832V13.7163H16.6382V11.7163ZM5.7832 12.7163V13.5496H7.7832V12.7163H5.7832ZM6.7832 14.5496H16.6399V12.5496H6.7832V14.5496Z\" fill=\"#CC092F\" mask=\"url(.path-1-inside-1_2439_3058)\"\/>\n<circle cx=\"12.6172\" cy=\"13.1329\" r=\"12\" stroke=\"#CC092F\"\/>\n<\/svg><\/a>\n        <\/h3>\n        <div class=\"excerpt\">Soluciones de preparaci\u00f3n de alto rendimiento<\/div>\n    <\/div>\n\n            <div class=\"image\">\n                            \n<div class=\"image-auto\" style=\"aspect-ratio: 1400 \/ 888;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:305,v:1\/cpm\/wp-content\/uploads\/2024\/05\/crushspecialty-preparation-hero.jpg?s=262c16f6\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:381,v:1\/cpm\/wp-content\/uploads\/2024\/05\/crushspecialty-preparation-hero.jpg?s=b433cc78\" width=\"1400\" height=\"888\" alt=\"crush specialty preparation\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n                    <\/div>\n\n    <\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_3fc2eb19c556e0a4c0cd595745282ec0\" class=\"nmc-block nmc-block--tabbed-ctas block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t\n\t<div class=\"block-wrap brown\">\n\t\t<div class=\"bound boundwider\">\n\t\t\t<div class=\"block-intro -mode-brown -w-link\">\n\t\t\t\t<div class=\"block-left\">\n\t\t\t\t\t                                                                                                                                                                                                                                                                                                                                <h2 class=\"block-title\">Garantizamos la calidad y eficiencia del producto con nuestros <strong>sistemas de automatizaci\u00f3n<\/strong><\/h2>\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/aftermarket-service\/automation\/\" target=\"\" class=\"btn -non-btn\">M\u00e1s sobre la automatizaci\u00f3n <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"12\" viewbox=\"0 0 17 12\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>arrow<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.9176 6.28571L8.65133 10.5863L9.42733 11.4286L16.3999 5.71429L9.41476 0L8.65362 0.860571L13.9153 5.14286L0.399902 5.14286L0.399902 6.28571L13.9176 6.28571Z\" fill=\"white\"\/>\n<\/svg><\/a>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"tabs\">\n\t\t\t\t<div class=\"tabs_list\" role=\"tablist\">\n\t\t\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"tab\" role=\"tab\" aria-controls=\"block_3fc2eb19c556e0a4c0cd595745282ec0-1\" id=\"tab-block_3fc2eb19c556e0a4c0cd595745282ec0-1\" tabindex=\"\">Servicios de automatizaci\u00f3n<\/button>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"tab-content\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tab_panel\" tabindex=\"0\" role=\"tabpanel\" id=\"block_3fc2eb19c556e0a4c0cd595745282ec0-1\" >\n\t\t\t\t\t\t\t<div class=\"tab-background\">\n\t\t\t\t\t\t\t\t<div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t<source media=\"(max-width: 499px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:800,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-liquids-tab1-automation.jpg?s=129d915f\">\n\t\t\t\t\t\t\t\t\t\t<source media=\"(max-width: 899px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:1200,h:724,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-liquids-tab1-automation.jpg?s=0e1463cd\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"eager\" style=\"aspect-ratio: 1.6578947368421;\" src=\"https:\/\/img.nmcdn.io\/e1\/w:1800,h:1086,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-liquids-tab1-automation.jpg?s=25781e87\" width=\"1800\" height=\"1086\" alt=\"\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"tab-wrap -left\">\n\t\t\t\t\t\t\t\t<div class=\"text -mode-dark\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"is-style-eyebrow-heading\">Servicios de automatizaci\u00f3n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                                                                                                                                                                                                                                                                                                                                                        <h2 class=\"block-title\">Optimice su proceso de prote\u00edna de origen vegetal con <strong>Nuestras soluciones completas de automatizaci\u00f3n.<\/strong><\/h2>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>La automatizaci\u00f3n puede mejorar significativamente el proceso de producci\u00f3n de prote\u00ednas de origen vegetal, mejorando la eficiencia y la calidad. CPM Crown es la \u00fanica fuente para gestionar todos los aspectos de la automatizaci\u00f3n de procesos. Combinamos nuestro hardware y nuestros instrumentos de sistemas con nuestra experiencia en software y un profundo conocimiento de los procesos para ofrecer soluciones que pueden ayudarlo a tomar decisiones en tiempo real con confianza y brindarle tranquilidad.<\/p>\n<p>A medida que su operaci\u00f3n basada en plantas crezca y la tecnolog\u00eda avance, seremos su socio de confianza que lo mantendr\u00e1 a la vanguardia.<\/p>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\t\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\n\t\n<div id=\"block_47f8f05d37e19ad7232845a3d4a787fc\" class=\"nmc-block nmc-block--split block-container -Width alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t\n\n<div class=\"split-half\">\n\t<div class=\"split-half-content\">\n\n\t\t\n\n<div class=\"split-half-image\">\n\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t<source media=\"(max-width: 400px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:500,h:700,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-plantbasedprotein-focus.jpg?s=9e68b9b4\">\n\t\t<img decoding=\"async\" loading=\"lazy\" style=\"aspect-ratio: 0.71428571428571;\" src=\"https:\/\/img.nmcdn.io\/e1\/w:800,h:1120,v:1\/cpm\/wp-content\/uploads\/2024\/05\/processes-plantbasedprotein-focus.jpg?s=dcad47ff\" width=\"800\" height=\"1120\" alt=\"Plant-Based Proteins processes\">\n\t<\/picture>\n<\/div>\n\n\n\t\t\n\t<\/div>\n<\/div>\n\n\n<div class=\"split-half\">\n\t<div class=\"split-half-content\">\n\n\t\t\n\n<p class=\"is-style-eyebrow-heading\">Nuestro enfoque<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Desbloquea el <strong>potencial <\/strong>de prote\u00edna de origen vegetal<\/h2>\n\n\n\n<p>No es de extra\u00f1ar que casi el 80% del concentrado de prote\u00edna de soja del mundo se produzca utilizando los equipos y soluciones de proceso de CPM Crown. En una industria en r\u00e1pido crecimiento, nadie tiene m\u00e1s conocimientos o experiencia que Crown de CPM. Conf\u00ede en nosotros para que le ayudemos a aprovechar esta industria en r\u00e1pido crecimiento.<\/p>\n\n\n\n\n\n\t\t\t\t\n\n<div class=\"nmc-block nmc-block--buttons\" id=\"block_5e42095dd2c39302a40658228cff01f2\">\n\t<div class=\"blockbody\">\n\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t<a href=\"https:\/\/onecpm.com\/es\/about-cpm\/contact-us\/\" class=\"btn -non-btn  -icon\" >Contacte con nuestro equipo de ventas<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"12\" viewbox=\"0 0 17 12\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>arrow<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.9176 6.28571L8.65133 10.5863L9.42733 11.4286L16.3999 5.71429L9.41476 0L8.65362 0.860571L13.9153 5.14286L0.399902 5.14286L0.399902 6.28571L13.9176 6.28571Z\" fill=\"white\"\/>\n<\/svg><\/a>\n\t\t<\/div>\n<\/div>\n\n\t\t\n\t<\/div>\n<\/div>\n\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\n<div id=\"block_b76de6a7577c2ff89bb29791c223f029\" class=\"nmc-block nmc-block--story-spotlight block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t<div class=\"content-wrap\">\n\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"is-style-eyebrow-heading\">Soluciones destacadas<\/p>\n\t\t\t\t\t\t\t\t                                                                                                                                                                                                                                                                                            <h2 class=\"block-title\">Un completo <strong>Soluci\u00f3n de procesamiento de prote\u00ednas vegetales<\/strong> Para nuestros clientes<\/h2>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/onecpm.com\/es\/the-latest\/success-stories\/\" target=\"\" class=\"btn -non-btn\">Ver todas las historias <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"12\" viewbox=\"0 0 17 12\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>arrow<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M13.9176 6.28571L8.65133 10.5863L9.42733 11.4286L16.3999 5.71429L9.41476 0L8.65362 0.860571L13.9153 5.14286L0.399902 5.14286L0.399902 6.28571L13.9176 6.28571Z\" fill=\"white\"\/>\n<\/svg><\/a>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"story-grid\">\n\t\t\t\t\t\t<div class=\"partial-wrapper\">\n\t\t\t\t\n<div class=\"partial -story -card\">\n    <div class=\"image\">\n        <div class=\"rect\">\n            \n<div class=\"image-auto\" style=\"aspect-ratio: 1280 \/ 760;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:285,v:1\/cpm\/wp-content\/uploads\/imported-files\/news-plant-based-protein.jpg?s=9d34dcbd\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:357,v:1\/cpm\/wp-content\/uploads\/imported-files\/news-plant-based-protein.jpg?s=27a6b1c5\" width=\"1280\" height=\"760\" alt=\"\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n        <\/div>\n        <div class=\"sq\">\n            \n<div class=\"image-auto\" style=\"aspect-ratio: 1280 \/ 1280;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:480,v:1\/cpm\/wp-content\/uploads\/imported-files\/news-plant-based-protein.jpg?s=c886e5c4\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:600,v:1\/cpm\/wp-content\/uploads\/imported-files\/news-plant-based-protein.jpg?s=fbc7e10e\" width=\"1280\" height=\"1280\" alt=\"\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n        <\/div> \n\n                <div class=\"type\">\n                            <svg width=\"60\" height=\"60\" viewbox=\"0 0 60 60\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>feed<\/title>\n<rect width=\"60\" height=\"60\" fill=\"#95578F\"\/>\n<path d=\"M30.0324 24.6489C26.0574 21.758 25.7412 15.931 29.3549 12.7289C29.6209 12.493 30.3185 12.3625 30.5594 12.5382C34.4039 15.2986 34.1229 22.0341 30.0324 24.6489Z\" fill=\"white\"\/>\n<path d=\"M24.7626 34.1249C24.6221 38.2003 21.5104 41.3171 17.4751 41.4275C16.4111 41.4576 15.8691 41.0611 15.849 39.9017C15.7887 35.9568 19.0109 32.4084 22.9408 32.1625C24.5669 32.0621 24.8229 32.3382 24.7626 34.1249Z\" fill=\"white\"\/>\n<path d=\"M24.7677 25.969C24.8078 27.6654 24.7074 27.7206 23.0612 27.7507C19.7236 27.816 15.9142 24.9401 15.8691 19.9613C15.859 18.9926 16.2907 18.5811 17.3296 18.5811C21.3849 18.571 24.6623 21.7882 24.7677 25.969Z\" fill=\"white\"\/>\n<path d=\"M26.8255 41.5778C26.7702 39.3042 27.6486 37.407 29.3048 35.821C29.8017 35.3493 30.1781 35.3643 30.7001 35.7809C34.0929 38.4962 34.0578 44.7698 30.6449 47.4148C30.0727 47.8565 29.7113 47.731 29.2546 47.2944C27.6385 45.7385 26.7903 43.8664 26.8255 41.5778Z\" fill=\"white\"\/>\n<path d=\"M37.079 27.7409C35.4529 27.7761 35.1618 27.6155 35.2069 26.3055C35.3826 21.1611 39.3174 18.4107 43.0315 18.5914C43.7944 18.6265 44.0252 18.9477 44.1055 19.6403C44.5773 23.8011 41.2497 27.6506 37.079 27.7409Z\" fill=\"white\"\/>\n<path d=\"M44.1207 39.711C44.1408 41.1916 43.8296 41.4877 42.3791 41.3873C38.3489 41.1063 35.3225 37.9694 35.187 33.9241C35.1418 32.5188 35.5383 32.1173 36.9386 32.1575C40.9036 32.2679 44.0655 35.5955 44.1157 39.706L44.1207 39.711Z\" fill=\"white\"\/>\n<path d=\"M32.2608 30.0647C32.2357 31.4098 31.2821 32.3484 29.9671 32.3082C28.6672 32.2681 27.7638 31.2743 27.809 29.9192C27.8491 28.6243 28.8881 27.5954 30.1177 27.6406C31.3474 27.6858 32.2859 28.7448 32.2608 30.0698V30.0647Z\" fill=\"white\"\/>\n<\/svg>\n                    <\/div>\n    <\/div>\n    <div class=\"text -mode-dark\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/success-story\/feeding-tomorrow-cpms-innovations-for-plant-based-protein-meat-alternatives\" class=\"link\">Alimentando el ma\u00f1ana: innovaciones de CPM para alternativas a la carne y las prote\u00ednas de origen vegetal<\/a>\n        <\/h3>\n    <\/div>\n<\/div>\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"partial-wrapper\">\n\t\t\t\t\n<div class=\"partial -story -card\">\n    <div class=\"image\">\n        <div class=\"rect\">\n            \n<div class=\"image-auto\" style=\"aspect-ratio: 1200 \/ 713;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:285,v:1\/cpm\/wp-content\/uploads\/2024\/08\/Pilot-Plant_liquids-1200x573-1.jpg?s=0ae1260c\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:357,v:1\/cpm\/wp-content\/uploads\/2024\/08\/Pilot-Plant_liquids-1200x573-1.jpg?s=52765da7\" width=\"1200\" height=\"713\" alt=\"Liquid Plant\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n        <\/div>\n        <div class=\"sq\">\n            \n<div class=\"image-auto\" style=\"aspect-ratio: 1200 \/ 1200;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:480,v:1\/cpm\/wp-content\/uploads\/2024\/08\/Pilot-Plant_liquids-1200x573-1.jpg?s=412a366e\">\n\t\t<img  loading=\"lazy\"src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:600,v:1\/cpm\/wp-content\/uploads\/2024\/08\/Pilot-Plant_liquids-1200x573-1.jpg?s=9095200f\" width=\"1200\" height=\"1200\" alt=\"Liquid Plant\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n        <\/div> \n\n                <div class=\"type\">\n                            <svg width=\"60\" height=\"60\" viewbox=\"0 0 60 60\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" role=\"img\" aria-hidden=\"true\" focusable=\"false\">\n\t<title>build<\/title>\n<rect width=\"60\" height=\"60\" fill=\"#377DAF\"\/>\n<path d=\"M32.2385 44.1507H27.6935C27.3884 43.213 27.0789 42.2753 26.7468 41.2658C25.9796 40.9383 25.172 40.5928 24.2792 40.2069C23.4402 40.6466 22.5608 41.1087 21.7801 41.517C20.6764 40.4223 19.6086 39.3634 18.433 38.1969C18.8099 37.4745 19.2631 36.5907 19.7387 35.6754C19.4201 34.9082 19.0926 34.1275 18.7157 33.2167C17.8408 32.9296 16.8672 32.6065 15.8442 32.27V27.6981C16.7685 27.393 17.7421 27.07 18.7022 26.7514C19.0477 25.9393 19.3797 25.1586 19.7476 24.3017C19.3124 23.4627 18.8593 22.5788 18.4645 21.8206C19.5771 20.7124 20.6405 19.649 21.8295 18.4645C22.4666 18.801 23.3459 19.2632 24.2612 19.7477C25.0688 19.4157 25.8809 19.0792 26.7468 18.7203C27.043 17.796 27.3481 16.8449 27.6666 15.8398H32.234C32.5391 16.7596 32.8577 17.7332 33.1852 18.7203C33.9749 19.0478 34.7555 19.3753 35.6439 19.7432C36.4874 19.3035 37.4027 18.8324 38.2731 18.3793C39.3723 19.4785 40.4177 20.5239 41.5304 21.6411C41.1042 22.4891 40.66 23.373 40.1934 24.2927C40.5254 25.1003 40.8619 25.9214 41.2074 26.7649C42.1226 27.0565 43.0379 27.3437 44.0205 27.6577V32.2924C43.1187 32.5841 42.1765 32.8847 41.2118 33.1943C40.8843 33.9839 40.5568 34.7646 40.1889 35.644C40.6061 36.4785 41.0548 37.3669 41.4631 38.1834C40.3549 39.2602 39.2736 40.3056 38.0667 41.4767C37.4475 41.1536 36.5726 40.6915 35.6574 40.2159C34.8812 40.5345 34.096 40.853 33.1852 41.2299C32.8981 42.1093 32.584 43.0829 32.2385 44.1462V44.1507ZM36.7745 29.9953C36.7745 26.1816 33.7057 23.0903 29.9413 23.1127C26.1995 23.1352 23.0947 26.2803 23.1126 30.0312C23.1306 33.7282 26.2354 36.8419 29.9234 36.8599C33.7012 36.8778 36.779 33.7955 36.779 29.9953H36.7745Z\" fill=\"white\"\/>\n<\/svg>\n                    <\/div>\n    <\/div>\n    <div class=\"text -mode-dark\">\n        <h3 class=\"heading\">\n            <a href=\"https:\/\/onecpm.com\/es\/success-story\/cpms-crown-celebrates-the-completion-of-the-global-innovation-center-gic-with-video-tour\" class=\"link\">CPM&#039;s Crown celebra la finalizaci\u00f3n del Centro de Innovaci\u00f3n Global (GIC) con un recorrido en v\u00eddeo<\/a>\n        <\/h3>\n    <\/div>\n<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n\n\t\n\n\t\t\t\t\t\t\t\n\t\n<div id=\"block_cb48557f82be91ee83736968d4962d7c\" class=\"nmc-block nmc-block--background block-container alignfull -mode-red filled padding-double\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"gutenberg\">\n\t\n\n\n\t\n\n\t\t\t\n\t\n<div id=\"block_dc1a258ddd40531a9d32f518d882b3c0\" class=\"nmc-block nmc-block--split block-container -Width alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t<div class=\"bound boundwider\">\n\t\t\n\n<div class=\"split-half\">\n\t<div class=\"split-half-content\">\n\n\t\t\n\n<h2 class=\"wp-block-heading\"><strong>Innovaci\u00f3n<\/strong> est\u00e1 en el coraz\u00f3n de <strong>Todo lo que hacemos.<\/strong><\/h2>\n\n\n\n<p>Descubra usted mismo lo que nuestras soluciones pueden hacer por usted.<\/p>\n\n\n\n\n\n\t\t\t\t\n\n<div class=\"nmc-block nmc-block--buttons\" id=\"block_26a8ea5abb87edff3aaf7fdf474c14be\">\n\t<div class=\"blockbody\">\n\t\n\t\t\t\t\t\t\n\t\t<a href=\"https:\/\/onecpm.com\/es\/about-cpm\/contact-us\/\" class=\"btn -btn\" >Cont\u00e1ctenos<\/a>\n\t\t<\/div>\n<\/div>\n\n\t\t\n\t<\/div>\n<\/div>\n\n\n<div class=\"split-half\">\n\t<div class=\"split-half-content\">\n\n\t\t\n\n\n\t\n\n\t\t\t\t\n\t\n<div id=\"block_5313baf45ba4959c8504c4ff720c3398\" class=\"nmc-block nmc-block--video block-container aligncontent\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\n\t\t<div class=\"video_wrap\">\n\t\t\t<a  href=\"https:\/\/www.youtube.com\/watch?v=jH87udY59ek\"  data-video-id=\"jH87udY59ek\" aria-label=\"Reproducir v\u00eddeo incrustado\" data-video-source=\"youtube\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t\t<source media=\"(max-width: 500px)\" srcset=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:338,v:1\/cpm\/wp-content\/uploads\/2024\/03\/innovation-center-video.png?s=3aae56d0\">\n\t\t\t\t\t\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" style=\"aspect-ratio: 1.7777777777778;\" src=\"https:\/\/img.nmcdn.io\/e1\/w:800,h:450,v:1\/cpm\/wp-content\/uploads\/2024\/03\/innovation-center-video.png?s=d8b7572f\" width=\"800\" height=\"450\" alt=\"innovation center\">\n\t\t\t\t<\/picture>\n\t\t\t\t\t\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\t\t\n\t<\/div>\n<\/div>\n\n\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>","protected":false},"template":"","class_list":["post-906","process-category","type-process-category","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/es\/wp-json\/wp\/v2\/process-category\/906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/es\/wp-json\/wp\/v2\/process-category"}],"about":[{"href":"https:\/\/onecpm.com\/es\/wp-json\/wp\/v2\/types\/process-category"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/es\/wp-json\/wp\/v2\/media?parent=906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}