{"id":5446,"date":"2024-07-12T22:48:07","date_gmt":"2024-07-12T22:48:07","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/?post_type=person&#038;p=5446"},"modified":"2024-08-27T16:03:19","modified_gmt":"2024-08-27T16:03:19","slug":"dibyava-ghosh","status":"publish","type":"person","link":"https:\/\/onecpm.com\/fr\/people\/dibyava-ghosh","title":{"rendered":"Dibyava Ghosh"},"content":{"rendered":"<div id=\"block_db5a7c6e2f67baac48cc1b14385c2282\" class=\"nmc-block nmc-block--masthead-person block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"bound boundwider wrap\">\n\t<div class=\"masthead-image\">\n\t\t\n<div class=\"image-auto\" style=\"aspect-ratio: 600 \/ 608;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:487,v:1\/cpm\/wp-content\/uploads\/2024\/07\/about-dibyavaghosh-1.jpg?s=6c0f8f0b\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:608,v:1\/cpm\/wp-content\/uploads\/2024\/07\/about-dibyavaghosh-1.jpg?s=057f500f\" width=\"600\" height=\"608\" alt=\"Dibyava Ghosh Profile picture\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n\t<\/div>\n\t<div class=\"masthead-content\">\n\t\t<p class=\"is-style-eyebrow-heading\">\u00c0 propos de CPM \/ <a href=\"\/fr\/leadership\/\">Direction<\/a><\/p>\n\t\t<h1 class=\"page-title\">Dibyava Ghosh<\/h1>\n\t\t<div class=\"job-title\">Pr\u00e9sident, Solutions de processus<\/div>\t\t\t\t\n\t\t\t\t\t<div class=\"bio\"><div class=\"index-module__VFezl\">\n<div class=\"styles-module__E0GIb\">\n<p><span class=\"styles-module__ypzdS\">Dibyava a rejoint CPM en 2024 en tant que pr\u00e9sident de l&#039;activit\u00e9 Process Solutions de CPM. Dibyava a plus de 20 ans d&#039;exp\u00e9rience en leadership dans le domaine de la fabrication industrielle et sa vaste exp\u00e9rience comprend des r\u00f4les importants tels que directeur g\u00e9n\u00e9ral chez Parker Hannifin, directeur g\u00e9n\u00e9ral mondial chez IMI et pr\u00e9sident chez Hill &amp; Smith, o\u00f9 elle \u00e9tait responsable du P&amp;L, de la strat\u00e9gie. , op\u00e9rations, ventes, marketing et finances. Dibyava poss\u00e8de une exp\u00e9rience mondiale et une expertise interfonctionnelle en ing\u00e9nierie, gestion de produits, gestion de la cha\u00eene d&#039;approvisionnement et gestion commerciale et P&amp;L. Elle est titulaire d&#039;une ma\u00eetrise \u00e8s sciences en g\u00e9nie \u00e9lectrique et \u00e9lectronique de l&#039;Illinois Institute of Technology et d&#039;une ma\u00eetrise en administration des affaires avec distinction de la Kellogg School of Management de l&#039;Universit\u00e9 Northwestern, o\u00f9 elle a \u00e9galement re\u00e7u le prix du doyen pour la r\u00e9ussite exceptionnelle des \u00e9tudiants.<\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>","protected":false},"template":"","class_list":["post-5446","person","type-person","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/fr\/wp-json\/wp\/v2\/person\/5446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/fr\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/onecpm.com\/fr\/wp-json\/wp\/v2\/types\/person"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/fr\/wp-json\/wp\/v2\/media?parent=5446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}