{"id":1413,"date":"2019-09-09T13:24:00","date_gmt":"2019-09-09T13:24:00","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/?post_type=news&#038;p=1413"},"modified":"2025-04-08T10:54:34","modified_gmt":"2025-04-08T10:54:34","slug":"new-world-class-facility-fuels-customer-success","status":"publish","type":"news","link":"https:\/\/onecpm.com\/pt_br\/news\/new-world-class-facility-fuels-customer-success","title":{"rendered":"Nova instala\u00e7\u00e3o de classe mundial impulsiona o sucesso do cliente"},"content":{"rendered":"<div id=\"block_44b79d00df75e8ca703b783b4de0ce17\" class=\"nmc-block nmc-block--masthead-news block-container\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"masthead-content\">\n\t<p class=\"small-heading\">Not\u00edcias<\/p>\n\t<h1 class=\"page-title\">Nova instala\u00e7\u00e3o de classe mundial impulsiona o sucesso do cliente<\/h1>\n\t<div class=\"post-meta\">\n\t\t\t\t\t<span>9 de setembro de 2019<\/span>\n\t\t\t<span>CPM<\/span>\n\t\t\t<\/div>\n\t<div class=\"post-share\">\n\t\tCompartilhar: <div class=\"share-links\">\n\t\t\t\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=%23https%3A%2F%2Fonecpm.com%2Fpt_br%2Fnews%2Fnew-world-class-facility-fuels-customer-success\" class=\"share-link -facebook\" aria-label=\"Compartilhe isso no Facebook\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>facebook<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M19.9415 9.96682C19.9415 4.46014 15.4774 -0.00390625 9.97073 -0.00390625C4.46404 -0.00390625 0 4.46014 0 9.96682C0 14.9435 3.64615 19.0684 8.4128 19.8164V12.849H5.88117V9.96682H8.4128V7.77014C8.4128 5.27123 9.90136 3.89091 12.1789 3.89091C13.2698 3.89091 14.4108 4.08565 14.4108 4.08565V6.53938H13.1535C11.9149 6.53938 11.5287 7.30797 11.5287 8.09647V9.96682H14.294L13.8519 12.849H11.5287V19.8164C16.2953 19.0684 19.9415 14.9435 19.9415 9.96682Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t<a href=\"https:\/\/twitter.com\/intent\/tweet?text=New%20World-Class%20Facility%20Fuels%20Customer%20Success%20-%20https%3A%2F%2Fonecpm.com%2Fpt_br%2Fnews%2Fnew-world-class-facility-fuels-customer-success\" class=\"share-link -x\" aria-label=\"Compartilhe isso no X\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"16\" viewbox=\"0 0 17 16\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>x\/twitter<\/title>\n<path d=\"M0.0399611 0.665283L6.36805 9.12654L0 16.0059H1.43319L7.00841 9.98292L11.513 16.0059H16.3902L9.70611 7.06871L15.6334 0.665283H14.2002L9.06575 6.21233L4.91717 0.665283H0.0399611ZM2.14758 1.72098H4.38818L14.2823 14.95H12.0417L2.14758 1.72098Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t<a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/onecpm.com\/pt_br\/news\/new-world-class-facility-fuels-customer-success\" class=\"share-link -linkedin\" aria-label=\"Compartilhe isso no LinkedIn\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>linkedin<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.4182 16.4187H13.5627V11.9474C13.5627 10.8812 13.5424 9.50943 12.0775 9.50943C10.5901 9.50943 10.3631 10.6703 10.3631 11.8703V16.4187H7.50874V7.224H10.248V8.48018H10.2877C10.6687 7.75709 11.6016 6.99492 12.9916 6.99492C15.8835 6.99492 16.4182 8.89874 16.4182 11.3752V16.4187ZM4.28666 5.96621C3.3682 5.96621 2.62851 5.22384 2.62851 4.30914C2.62851 3.3955 3.3682 2.6526 4.28666 2.6526C5.20083 2.6526 5.94319 3.3955 5.94319 4.30914C5.94319 5.22384 5.20083 5.96621 4.28666 5.96621ZM2.85545 7.224H5.71626V16.4187H2.85545V7.224ZM17.8414 0H1.42104C0.636924 0 0 0.621937 0 1.38839V17.8778C0 18.6453 0.636924 19.2683 1.42104 19.2683H17.8414C18.6271 19.2683 19.2688 18.6453 19.2688 17.8778V1.38839C19.2688 0.621937 18.6271 0 17.8414 0Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t\n\t\n\t<a href=\"mailto:?&#038;body=New World-Class Facility Fuels Customer Success - https:\/\/onecpm.com\/pt_br\/news\/new-world-class-facility-fuels-customer-success\" class=\"share-link -email\" aria-label=\"Compartilhe isso no LinkedIn\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>email<\/title>\n<g clip-path=\"url(#clip0_3673_20047)\">\n<path d=\"M15.8333 7.55164C15.8333 7.55164 11.51 7.27414 10 9.16664C11.6667 5.08664 15.8333 4.2183 15.8333 4.2183V2.55164L20 5.88497L15.8333 9.23414V7.55164ZM0.0216667 20H19.9775L10 10.3275L0.0216667 20ZM1.41583 8.3333L9.99167 2.0933L12.5358 3.94164C13.1292 3.55914 13.695 3.2708 14.1633 3.0633L9.99167 0.0324707L0 7.3033V17.7L6.12667 11.7608L1.41583 8.3333ZM14.5433 12.41L20 17.7V8.0233L14.5433 12.41Z\" fill=\"#666666\"\/>\n<\/g>\n<defs>\n<clippath id=\"clip0_3673_20047\">\n<rect width=\"20\" height=\"20\" fill=\"white\"\/>\n<\/clippath>\n<\/defs>\n<\/svg>\t<\/a>\n<\/div>\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n<h3 class=\"wp-block-heading\"><em>A sede global e o centro de inova\u00e7\u00e3o da Crown j\u00e1 est\u00e3o abertos<\/em><\/h3>\n\n\n\n<p>BLAINE, Minnesota, EUA 31 de agosto de 2019 \u2013 Ap\u00f3s anos de planejamento e oito meses de constru\u00e7\u00e3o do zero, a Crown revela sua nova sede global e centro de inova\u00e7\u00e3o em Blaine, Minnesota, EUA. A instala\u00e7\u00e3o de 68.000 p\u00e9s quadrados e $12 milh\u00f5es acomoda mais funcion\u00e1rios e alimenta avan\u00e7os tecnol\u00f3gicos para a empresa e seus clientes por meio de seu centro de inova\u00e7\u00e3o de \u00faltima gera\u00e7\u00e3o \u2014 um ambiente de seguran\u00e7a em primeiro lugar que oferece suporte e otimiza solu\u00e7\u00f5es de processos personalizados e treinamentos extensivos para clientes em sua planta piloto de 15.000 p\u00e9s quadrados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"280\" src=\"https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/hero-shot-outside-of-bldg-420x280-1.jpg\" alt=\"\" class=\"wp-image-1452\" srcset=\"https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/hero-shot-outside-of-bldg-420x280-1.jpg 420w, https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/hero-shot-outside-of-bldg-420x280-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/figure>\n\n\n\n<p>A sede global e o centro de inova\u00e7\u00e3o da Crown servem como um recurso de classe mundial para os principais fabricantes globais nas ind\u00fastrias de processamento de sementes oleaginosas e especiais. Estabelecendo um novo padr\u00e3o da ind\u00fastria, o principal centro de inova\u00e7\u00e3o da Crown inclui uma planta piloto totalmente funcional e altamente instrumentada com uma sala de controle computadorizada (controles PLC, com integra\u00e7\u00e3o HMI) para monitoramento de processo e coleta de dados de todas as \u00e1reas da planta, incluindo prepara\u00e7\u00e3o, extra\u00e7\u00e3o, refino, biodiesel, diesel renov\u00e1vel e processamento oleoqu\u00edmico.<\/p>\n\n\n\n<p>&nbsp;\u201cNossa planta piloto permite que os clientes simulem opera\u00e7\u00f5es de planta, testes, processamento de ped\u00e1gio, novas tecnologias e testes de produtos em um ambiente confidencial e controlado que economiza tempo, dinheiro e dores de cabe\u00e7a\u201d, diz Bill Antilla, gerente geral da Crown Global Companies. \u201cOs clientes tamb\u00e9m podem capacitar os funcion\u00e1rios com treinamento abrangente para melhorar o conhecimento do processo, a experi\u00eancia em manuten\u00e7\u00e3o e a seguran\u00e7a da planta.\u201d O Innovation Center apresenta v\u00e1rios locais de treinamento, incluindo salas de aula grandes e pequenas, uma \u00e1rea de treinamento pr\u00e1tico de equipamentos, a sala de caldeiras da planta piloto que oferece treinamento de vapor e condensa\u00e7\u00e3o do mundo real e o centro de controle de motores onde demonstra\u00e7\u00f5es de seguran\u00e7a e treinamento t\u00e9cnico promovem o uso e o manuseio seguros de energia.<\/p>\n\n\n\n<p>\u201cNosso objetivo \u00e9 ser a &#039;primeira chamada&#039; para l\u00edderes da ind\u00fastria de sementes oleaginosas que precisam de um parceiro de tecnologia comprometido em descobrir abordagens inovadoras para reduzir o uso de energia e \u00e1gua, melhorar os rendimentos e reduzir os custos de capital e operacionais\u201d, diz Mike Hoerle, vice-presidente de engenharia global da Crown.<\/p>\n\n\n\n<p>Al\u00e9m de atender a solicita\u00e7\u00f5es espec\u00edficas do cliente, o Innovation Center tamb\u00e9m apresenta um Skunk Works R&amp;D Workshop, onde a equipe de P&amp;D da Crown desenvolve solu\u00e7\u00f5es disruptivas para impulsionar avan\u00e7os do setor. \u201cNossa sede global e Innovation Center aproveitam totalmente a tecnologia l\u00edder do setor da Crown e a talentosa equipe global para expandir ainda mais o papel da Crown como consultora confi\u00e1vel e parceira de solu\u00e7\u00e3o de problemas para nossos clientes\u201d, acrescenta Antilla.<\/p>\n\n\n\n<p>Para agendar uma visita \u00e0 sede global e ao centro de inova\u00e7\u00e3o do Crown ou para solicitar um folheto com uma vis\u00e3o geral destacando as \u00e1reas funcionais de contato do centro de inova\u00e7\u00e3o:&nbsp;<a href=\"mailto:Kris.Knudson@crowniron.com\">Kris.Knudson@crowniron.com<\/a>.<\/p>\n\n\n\n<p>A Crown, uma divis\u00e3o da CPM Holdings Inc., \u00e9 uma empresa global com 140 anos de exist\u00eancia, sediada em Minnesota, com escrit\u00f3rios adicionais no Reino Unido, Argentina, Brasil, China, Alemanha, Honduras, M\u00e9xico, R\u00fassia e Ucr\u00e2nia. A Crown emprega atualmente 250 pessoas em todo o mundo. <\/p>","protected":false},"template":"","class_list":["post-1413","news","type-news","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":2,"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1413\/revisions"}],"predecessor-version":[{"id":4482,"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1413\/revisions\/4482"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/media?parent=1413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}