{"id":1414,"date":"2019-05-15T13:24:00","date_gmt":"2019-05-15T13:24:00","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/?post_type=news&#038;p=1414"},"modified":"2024-07-02T20:11:17","modified_gmt":"2024-07-02T20:11:17","slug":"crown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair","status":"publish","type":"news","link":"https:\/\/onecpm.com\/pt_br\/news\/crown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair","title":{"rendered":"Crown apresenta solu\u00e7\u00e3o patenteada para simplificar a limpeza, manuten\u00e7\u00e3o e reparo do condicionador de sementes"},"content":{"rendered":"<div id=\"block_d2aa5afd24cd9fb071ca8d8ef0f2b92e\" class=\"nmc-block nmc-block--masthead-news block-container\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"masthead-content\">\n\t<p class=\"small-heading\">Not\u00edcias<\/p>\n\t<h1 class=\"page-title\">Crown apresenta solu\u00e7\u00e3o patenteada para simplificar a limpeza, manuten\u00e7\u00e3o e reparo do condicionador de sementes<\/h1>\n\t<div class=\"post-meta\">\n\t\t\t\t\t<span>15 de maio de 2019<\/span>\n\t\t\t<span>CPM<\/span>\n\t\t\t<\/div>\n\t<div class=\"post-share\">\n\t\tCompartilhar: <div class=\"share-links\">\n\t\t\t\t<a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=%23https%3A%2F%2Fonecpm.com%2Fpt_br%2Fnews%2Fcrown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair\" class=\"share-link -facebook\" aria-label=\"Compartilhe isso no Facebook\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>facebook<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M19.9415 9.96682C19.9415 4.46014 15.4774 -0.00390625 9.97073 -0.00390625C4.46404 -0.00390625 0 4.46014 0 9.96682C0 14.9435 3.64615 19.0684 8.4128 19.8164V12.849H5.88117V9.96682H8.4128V7.77014C8.4128 5.27123 9.90136 3.89091 12.1789 3.89091C13.2698 3.89091 14.4108 4.08565 14.4108 4.08565V6.53938H13.1535C11.9149 6.53938 11.5287 7.30797 11.5287 8.09647V9.96682H14.294L13.8519 12.849H11.5287V19.8164C16.2953 19.0684 19.9415 14.9435 19.9415 9.96682Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t<a href=\"https:\/\/twitter.com\/intent\/tweet?text=Crown%20Introduces%20Patented%20Solution%20to%20Simplify%20Seed%20Conditioner%20Cleaning%2C%20Maintenance%20and%20Repair%20-%20https%3A%2F%2Fonecpm.com%2Fpt_br%2Fnews%2Fcrown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair\" class=\"share-link -x\" aria-label=\"Compartilhe isso no X\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"17\" height=\"16\" viewbox=\"0 0 17 16\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>x\/twitter<\/title>\n<path d=\"M0.0399611 0.665283L6.36805 9.12654L0 16.0059H1.43319L7.00841 9.98292L11.513 16.0059H16.3902L9.70611 7.06871L15.6334 0.665283H14.2002L9.06575 6.21233L4.91717 0.665283H0.0399611ZM2.14758 1.72098H4.38818L14.2823 14.95H12.0417L2.14758 1.72098Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t<a href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&#038;url=https:\/\/onecpm.com\/pt_br\/news\/crown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair\" class=\"share-link -linkedin\" aria-label=\"Compartilhe isso no LinkedIn\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>linkedin<\/title>\n<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16.4182 16.4187H13.5627V11.9474C13.5627 10.8812 13.5424 9.50943 12.0775 9.50943C10.5901 9.50943 10.3631 10.6703 10.3631 11.8703V16.4187H7.50874V7.224H10.248V8.48018H10.2877C10.6687 7.75709 11.6016 6.99492 12.9916 6.99492C15.8835 6.99492 16.4182 8.89874 16.4182 11.3752V16.4187ZM4.28666 5.96621C3.3682 5.96621 2.62851 5.22384 2.62851 4.30914C2.62851 3.3955 3.3682 2.6526 4.28666 2.6526C5.20083 2.6526 5.94319 3.3955 5.94319 4.30914C5.94319 5.22384 5.20083 5.96621 4.28666 5.96621ZM2.85545 7.224H5.71626V16.4187H2.85545V7.224ZM17.8414 0H1.42104C0.636924 0 0 0.621937 0 1.38839V17.8778C0 18.6453 0.636924 19.2683 1.42104 19.2683H17.8414C18.6271 19.2683 19.2688 18.6453 19.2688 17.8778V1.38839C19.2688 0.621937 18.6271 0 17.8414 0Z\" fill=\"#666666\"\/>\n<\/svg>\t<\/a>\n\t\n\t\n\t<a href=\"mailto:?&#038;body=Crown Introduces Patented Solution to Simplify Seed Conditioner Cleaning, Maintenance and Repair - https:\/\/onecpm.com\/pt_br\/news\/crown-introduces-patented-solution-to-simplify-seed-conditioner-cleaning-maintenance-and-repair\" class=\"share-link -email\" aria-label=\"Compartilhe isso no LinkedIn\" target=\"_blank\">\n\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewbox=\"0 0 20 20\" fill=\"none\" role=\"img\" aria-hidden=\"true\" focusable=\"false\"><title>email<\/title>\n<g clip-path=\"url(#clip0_3673_20047)\">\n<path d=\"M15.8333 7.55164C15.8333 7.55164 11.51 7.27414 10 9.16664C11.6667 5.08664 15.8333 4.2183 15.8333 4.2183V2.55164L20 5.88497L15.8333 9.23414V7.55164ZM0.0216667 20H19.9775L10 10.3275L0.0216667 20ZM1.41583 8.3333L9.99167 2.0933L12.5358 3.94164C13.1292 3.55914 13.695 3.2708 14.1633 3.0633L9.99167 0.0324707L0 7.3033V17.7L6.12667 11.7608L1.41583 8.3333ZM14.5433 12.41L20 17.7V8.0233L14.5433 12.41Z\" fill=\"#666666\"\/>\n<\/g>\n<defs>\n<clippath id=\"clip0_3673_20047\">\n<rect width=\"20\" height=\"20\" fill=\"white\"\/>\n<\/clippath>\n<\/defs>\n<\/svg>\t<\/a>\n<\/div>\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>\n\n\n<p>ROSEVILLE, Minnesota, 1\u00ba de maio de 2019 \u2013 A Crown, l\u00edder na ind\u00fastria de processamento de sementes oleaginosas, apresenta uma solu\u00e7\u00e3o revolucion\u00e1ria e patenteada para fabricantes de sementes oleaginosas: a Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"253\" src=\"https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/2-Tier-Close-420x253-1.jpg\" alt=\"\" class=\"wp-image-1454\" srcset=\"https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/2-Tier-Close-420x253-1.jpg 420w, https:\/\/onecpm.com\/wp-content\/uploads\/2024\/04\/2-Tier-Close-420x253-1-300x181.jpg 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/figure>\n\n\n\n<p>Desenvolvido em resposta \u00e0s necessidades do cliente, este primeiro da ind\u00fastria da Crown oferece flexibilidade sem precedentes para limpeza, manuten\u00e7\u00e3o e reforma de se\u00e7\u00f5es de aquecimento do condicionador de sementes. O design inovador da Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular da Crown apresenta 16 m\u00f3dulos de tubo remov\u00edveis na se\u00e7\u00e3o de aquecimento, permitindo que os operadores de esmagamento e prepara\u00e7\u00e3o de sementes oleaginosas identifiquem, isolem e mitiguem problemas sem desempilhamento, grandes paradas, autoriza\u00e7\u00f5es ou guindastes. O design da Crown usa conex\u00f5es aparafusadas para agilizar a remo\u00e7\u00e3o e a substitui\u00e7\u00e3o do m\u00f3dulo, eliminando as inefici\u00eancias e os riscos de seguran\u00e7a do corte ou soldagem no local ou no ambiente da planta. Para facilitar a solu\u00e7\u00e3o de problemas, o design tamb\u00e9m inclui visores que fornecem aos operadores acesso visual \u00e0 se\u00e7\u00e3o de aquecimento fechada.<\/p>\n\n\n\n<p>A Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular Crown est\u00e1 atualmente funcionando com sucesso em um ambiente de produ\u00e7\u00e3o do cliente. Testes de campo da Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular demonstram qualidade consistente do produto e uma redu\u00e7\u00e3o significativa em paradas de manuten\u00e7\u00e3o, encurtando a interrup\u00e7\u00e3o de 10 dias para menos de 24 horas. Para melhor desempenho operacional, tubos comprometidos podem ser isolados com perda m\u00ednima de superf\u00edcie de aquecimento, e a Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular Crown \u00e9 capaz de funcionar em press\u00f5es operacionais mais altas, de at\u00e9 45 psi. Ideal para sistemas de descasque a frio e convencionais, a Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular Crown est\u00e1 dispon\u00edvel em a\u00e7o inoxid\u00e1vel e a\u00e7o carbono, e pode ser adaptada em Condicionadores de Sementes Verticais Crown existentes.<\/p>\n\n\n\n<p>\u201cEstamos entusiasmados em oferecer aos clientes maior flexibilidade operacional e a capacidade de reduzir o tempo de inatividade e seus custos associados com nossa inovadora Se\u00e7\u00e3o de Aquecimento do Condicionador de Sementes Vertical Modular\u201d, diz Bill Antilla, Gerente Geral da Crown Global Companies. \u201cA capacidade da Crown de fornecer solu\u00e7\u00f5es e tecnologias mais inovadoras acelerar\u00e1 ainda mais quando nosso novo Centro de Inova\u00e7\u00e3o Global for inaugurado no final deste ano.\u201d<\/p>\n\n\n\n<p>A sede global Crown de 68.000 p\u00e9s quadrados e o centro de inova\u00e7\u00e3o de classe mundial est\u00e3o atualmente em constru\u00e7\u00e3o em Blaine, MN. Esta instala\u00e7\u00e3o de \u00faltima gera\u00e7\u00e3o incluir\u00e1 uma planta totalmente funcional de 15.000 p\u00e9s quadrados com equipamentos de prepara\u00e7\u00e3o, extra\u00e7\u00e3o e refino conectados a um sistema abrangente de aquisi\u00e7\u00e3o de dados. Os clientes poder\u00e3o simular opera\u00e7\u00f5es de processamento de plantas em um ambiente controlado para dar suporte a testes e treinamentos de clientes. O centro servir\u00e1 como um recurso de classe mundial para fabricantes globais de sementes oleaginosas, ajudando-os a otimizar as capacidades de fabrica\u00e7\u00e3o reduzindo o uso de energia e \u00e1gua, melhorando os rendimentos e reduzindo os custos de capital e operacionais.<\/p>\n\n\n\n<p>A Crown, uma divis\u00e3o da CPM Holdings Inc., \u00e9 uma empresa global de 141 anos, sediada em Minnesota, com escrit\u00f3rios adicionais no Reino Unido, Argentina, Brasil, China, Alemanha, Honduras, M\u00e9xico, R\u00fassia e Ucr\u00e2nia. A Crown emprega atualmente 250 pessoas em todo o mundo. <\/p>","protected":false},"template":"","class_list":["post-1414","news","type-news","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/types\/news"}],"version-history":[{"count":2,"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1414\/revisions"}],"predecessor-version":[{"id":4483,"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/news\/1414\/revisions\/4483"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/media?parent=1414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}