{"id":2054,"date":"2024-05-13T15:40:27","date_gmt":"2024-05-13T15:40:27","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/?post_type=person&#038;p=2054"},"modified":"2024-06-13T19:00:27","modified_gmt":"2024-06-13T19:00:27","slug":"morgan-boyd","status":"publish","type":"person","link":"https:\/\/onecpm.com\/pt_br\/people\/morgan-boyd","title":{"rendered":"Morgan Boyd"},"content":{"rendered":"<div id=\"block_4f7cda1d9bcc7063bdf2bb43454a09ae\" class=\"nmc-block nmc-block--masthead-person block-container alignfull\">\n\t\n\t\t\n\t\t\t<div class=\"blockbody\">\n\t\t\t\t<div class=\"bound boundwider wrap\">\n\t<div class=\"masthead-image\">\n\t\t\n<div class=\"image-auto\" style=\"aspect-ratio: 590 \/ 598;\">\n\t<picture>\n\t\t<source \n\t\t\tmedia=\"(max-width: 600px)\"\n\t\t\tsrcset=\"https:\/\/img.nmcdn.io\/e1\/w:480,h:487,v:1\/cpm\/wp-content\/uploads\/2024\/05\/cpm-team-Morgan-Boyd.jpg.webp?s=41801583\">\n\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/img.nmcdn.io\/e1\/w:600,h:608,v:1\/cpm\/wp-content\/uploads\/2024\/05\/cpm-team-Morgan-Boyd.jpg.webp?s=1aed2756\" width=\"590\" height=\"598\" alt=\"\" aria-hidden=\"true\">\n\t<\/picture>\n<\/div>\n\t<\/div>\n\t<div class=\"masthead-content\">\n\t\t<p class=\"is-style-eyebrow-heading\">Sobre CPM\/ <a href=\"\/pt_br\/leadership\/\">Lideran\u00e7a<\/a><\/p>\n\t\t<h1 class=\"page-title\">Morgan Boyd<\/h1>\n\t\t<div class=\"job-title\">Vice-presidente, Tecnologia da Informa\u00e7\u00e3o<\/div>\t\t\t\t\n\t\t\t\t\t<div class=\"bio\"><p>Morgan traz 30 anos de experi\u00eancia para CPM enquanto dirige a equipe global de tecnologia da informa\u00e7\u00e3o CPM. Morgan ingressou na CPM em 2014 e se concentrou na constru\u00e7\u00e3o de infraestrutura em nuvem de ponta, plataformas modernas de seguran\u00e7a digital e um sistema ERP global unificado. O suporte ao cliente de classe mundial \u00e9 fundamental para a vis\u00e3o de sucesso da TI CPM. Com uma equipe global de TI de classe mundial e a experi\u00eancia da Morgan no setor banc\u00e1rio e militar, o CPM est\u00e1 posicionado para permanecer seguro e est\u00e1vel para o sucesso a longo prazo. Morgan formou-se no Programa Avan\u00e7ado de Engenharia de Sistemas de Dados da Marinha dos Estados Unidos e especializou-se em sistemas de defesa antim\u00edsseis. Ele serviu seu pa\u00eds na Frota do Atl\u00e2ntico.<\/p>\n<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\t\n\t<\/div>","protected":false},"template":"","class_list":["post-2054","person","type-person","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/person\/2054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/types\/person"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/pt_br\/wp-json\/wp\/v2\/media?parent=2054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}