{"id":952,"date":"2023-12-01T05:00:00","date_gmt":"2023-12-01T05:00:00","guid":{"rendered":"https:\/\/cpm.epicenter1.com\/press\/mixing-up-in-the-lab"},"modified":"2024-04-11T15:30:28","modified_gmt":"2024-04-11T15:30:28","slug":"mixing-up-in-the-lab","status":"publish","type":"press","link":"https:\/\/onecpm.com\/th\/press\/mixing-up-in-the-lab","title":{"rendered":"\u0e01\u0e32\u0e23\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e41\u0e25\u0e47\u0e1b"},"template":"","class_list":["post-952","press","type-press","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/onecpm.com\/th\/wp-json\/wp\/v2\/press\/952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onecpm.com\/th\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/onecpm.com\/th\/wp-json\/wp\/v2\/types\/press"}],"wp:attachment":[{"href":"https:\/\/onecpm.com\/th\/wp-json\/wp\/v2\/media?parent=952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}